{"id":6678,"date":"2021-11-30T11:12:51","date_gmt":"2021-11-30T10:12:51","guid":{"rendered":"https:\/\/fairforce.one\/?page_id=6678"},"modified":"2025-07-21T16:16:24","modified_gmt":"2025-07-21T14:16:24","slug":"anspruchsrechner","status":"publish","type":"page","link":"https:\/\/fairforce.one\/en\/lp\/anspruchsrechner\/","title":{"rendered":"Claims calculator"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6678\" class=\"elementor elementor-6678\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e544fcd e-flex e-con-boxed e-con e-parent\" data-id=\"e544fcd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e6ff724 e-con-full e-flex e-con e-child\" data-id=\"e6ff724\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6314ccc elementor-widget elementor-widget-spacer\" data-id=\"6314ccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-604cf3c elementor-widget elementor-widget-heading\" data-id=\"604cf3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\" id=\"unfall\" title=\"Unfall?\">Unfall?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae05435 elementor-widget elementor-widget-heading\" data-id=\"ae05435\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wir k\u00fcmmern<br> uns!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0a72a1 elementor-widget elementor-widget-image\" data-id=\"c0a72a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"680\" src=\"https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/250600_header_2_1-1024x871.png\" class=\" attachment-large size-large wp-image-17105\" alt=\"Illustriertes Team aus Fachanwalt, Schadensregulierer und Pr\u00fcfern als Symbol f\u00fcr den fairforce.one Unfallconcierge-Service\" srcset=\"https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/250600_header_2_1-1024x871.png 1024w, https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/250600_header_2_1-300x255.png 300w, https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/250600_header_2_1-768x653.png 768w, https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/250600_header_2_1-14x12.png 14w, https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/250600_header_2_1.png 1204w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2386b29 elementor-widget-mobile__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2386b29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">kostenfreie Beratung <br>rechtssichere Unfallmeldung <br>schnell wieder mobil <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">fairforce koordiniert<br> <strong>Mietwagen, Gutachten, Werkstatt, alle Versicherungen <\/strong><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">bew\u00e4hrte Pr\u00fcfung, Durchsetzung und Auszahlung aller Schadenersatz-Arten<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ad0299 elementor-mobile-align-justify elementor-hidden-desktop elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"2ad0299\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#funnel\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-search-plus\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Unfall kostenfrei pr\u00fcfen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5655dcb e-con-full e-flex e-con e-child\" data-id=\"5655dcb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-958c2dd e-con-full e-flex e-con e-child\" data-id=\"958c2dd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-248d59c e-con-full e-flex e-con e-child\" data-id=\"248d59c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-274c8d2 elementor-widget elementor-widget-menu-anchor\" data-id=\"274c8d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"funnel\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ca2eeb elementor-widget elementor-widget-heading\" data-id=\"5ca2eeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"in-7-klicks-zum-bestbewerteten-service\" title=\"In 7 Klicks zum bestbewerteten Service. \">In 7 Klicks zum bestbewerteten Service. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e455053 elementor-widget elementor-widget-template\" data-id=\"e455053\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9014\" class=\"elementor elementor-9014\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9952903 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9952903\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e30d4db\" data-id=\"e30d4db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99f8162 fluent_form_sms_wrapper _no_validation fluent-form-widget-step-header-yes fluent-form-widget-step-progressbar-yes fluentform-widget-submit-button-custom elementor-widget elementor-widget-fluent-form-widget\" data-id=\"99f8162\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"fluent-form-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"fluentform-widget-wrapper fluentform-widget-align-default\">\n\n            \n            <div class='fluentform ff-default fluentform_wrapper_5 ffs_custom_wrap'><form data-form_id=\"5\" id=\"fluentform_5\" class=\"frm-fluent-form fluent_form_5 ff-el-form-top ff_form_instance_5_1 ff-form-loading ff-form-has-steps ffs_custom\" data-form_instance=\"ff_form_instance_5_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">240930 SMS-Funnel<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='6678' \/><input type=\"hidden\" id=\"_fluentform_5_fluentformnonce\" name=\"_fluentform_5_fluentformnonce\" value=\"aaa70500ce\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/6678\/\" \/><div class='ff-step-container' class=\"ff1_form_page_1\" data-name=\"step_start-5_8\" data-disable_auto_focus=\"no\" data-enable_auto_slider=\"no\" data-enable_step_data_persistency=\"no\" data-enable_step_page_resume=\"no\" data-animation_type=\"slide\" data-progress_layout=\"top\" data-progress_indicator=\"steps\" ><div class='ff-step-header'><ul class='ff-step-titles ff-step-titles-navs ff-step-titles--clickable' role='group' aria-label='Form steps' aria-live='polite'><li class=\"ff_active\"><span class=\"ff-step-title-text\">Step 1<\/span><\/li><li class=\"\"><span class=\"ff-step-title-text\">Step 2<\/span><\/li><li class=\"\"><span class=\"ff-step-title-text\">Step 3<\/span><\/li><li class=\"\"><span class=\"ff-step-title-text\">Step 4<\/span><\/li><li class=\"\"><span class=\"ff-step-title-text\">Step 5<\/span><\/li><\/ul><\/div><span class='ff_step_start'><\/span><div class='ff-step-body'><div class=\"ff1_form_page_1 fluentform-step active\" data-name=\"step_start-5_8\" data-disable_auto_focus=\"no\" data-enable_auto_slider=\"no\" data-enable_step_data_persistency=\"no\" data-enable_step_page_resume=\"no\" data-animation_type=\"slide\" data-progress_layout=\"top\" data-progress_indicator=\"steps\" ><input type=\"hidden\" name=\"additional_params\" data-name=\"additional_params\" ><input type=\"hidden\" name=\"is_weblead_funnel\" value=\"1\" data-name=\"is_weblead_funnel\" ><div class='ff-el-group choose_ff1 ff_list_buttons'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label   aria-label=\"Mit welchem Fahrzeug waren Sie unterwegs?\">Mit welchem Fahrzeug waren Sie unterwegs?<\/label><\/div><div class='ff-el-input--content'><div class=\"ff_el_checkable_photo_holders\"><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.online\/wp-content\/uploads\/2021\/10\/pkw1.svg)' class='ff-el-image-input-src' for='fahrzeugtyp_30fbe32a6330c8a09ec5262695720821' aria-label='Auto'><\/label><label class='ff-el-form-check-label' for='fahrzeugtyp_30fbe32a6330c8a09ec5262695720821'><input  type=\"radio\" name=\"fahrzeugtyp\" data-name=\"fahrzeugtyp\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"auto\"  id='fahrzeugtyp_30fbe32a6330c8a09ec5262695720821' aria-label='Auto' aria-invalid='false' aria-required=true> <span>Auto<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.online\/wp-content\/uploads\/2021\/10\/motorrad1.svg)' class='ff-el-image-input-src' for='fahrzeugtyp_285a41bf56f7876132f2ea949af0f08e' aria-label='Motorrad'><\/label><label class='ff-el-form-check-label' for='fahrzeugtyp_285a41bf56f7876132f2ea949af0f08e'><input  type=\"radio\" name=\"fahrzeugtyp\" data-name=\"fahrzeugtyp\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"motorrad\"  id='fahrzeugtyp_285a41bf56f7876132f2ea949af0f08e' aria-label='Motorrad' aria-invalid='false' aria-required=true> <span>Motorrad<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.online\/wp-content\/uploads\/2021\/10\/lkw1.svg)' class='ff-el-image-input-src' for='fahrzeugtyp_7f13213d027ef0174a3058ba9d0efe5d' aria-label='LKW'><\/label><label class='ff-el-form-check-label' for='fahrzeugtyp_7f13213d027ef0174a3058ba9d0efe5d'><input  type=\"radio\" name=\"fahrzeugtyp\" data-name=\"fahrzeugtyp\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"lkw\"  id='fahrzeugtyp_7f13213d027ef0174a3058ba9d0efe5d' aria-label='LKW' aria-invalid='false' aria-required=true> <span>LKW<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.one\/wp-content\/uploads\/2021\/10\/fahrrad1.svg)' class='ff-el-image-input-src' for='fahrzeugtyp_2beca1fe8c886274340896b6a44a9e3d' aria-label='Sonstiges'><\/label><label class='ff-el-form-check-label' for='fahrzeugtyp_2beca1fe8c886274340896b6a44a9e3d'><input  type=\"radio\" name=\"fahrzeugtyp\" data-name=\"fahrzeugtyp\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"sonstiges\"  id='fahrzeugtyp_2beca1fe8c886274340896b6a44a9e3d' aria-label='Sonstiges' aria-invalid='false' aria-required=true> <span>Sonstiges<\/span><\/label><\/div><\/div><\/div><\/div><div class='step-nav ff_step_nav_last'><button style='float: left;'  type='button' data-action='prev' class='ff-btn ff-btn-prev ff-btn-secondary' aria-label='Vorherige'>Vorherige<\/button><button style='float: right;'  type='button' data-action='next' class='ff-float-right ff-btn ff-btn-next ff-btn-secondary' aria-label='Jetzt anfragen'>Jetzt anfragen<\/button><\/div><\/div><div style='display: none;' class=\" fluentform-step\" data-name=\"form_step-5_1\" ><div class='ff-el-group choose_ff1 ff_list_buttons'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label   aria-label=\"Wurden Sie oder Mitfahrende verletzt?\">Wurden Sie oder Mitfahrende verletzt?<\/label><\/div><div class='ff-el-input--content'><div class=\"ff_el_checkable_photo_holders\"><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.online\/wp-content\/uploads\/2021\/10\/leicht-verletzt.svg)' class='ff-el-image-input-src' for='verletzung_d170bf8be48cef5d518a41ab40dbe8c0' aria-label='Leicht verletzt'><\/label><label class='ff-el-form-check-label' for='verletzung_d170bf8be48cef5d518a41ab40dbe8c0'><input  type=\"radio\" name=\"verletzung\" data-name=\"verletzung\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"leicht_verletzt\"  id='verletzung_d170bf8be48cef5d518a41ab40dbe8c0' aria-label='Leicht verletzt' aria-invalid='false' aria-required=true> <span>Leicht verletzt<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.online\/wp-content\/uploads\/2021\/10\/schwer-verletzt.svg)' class='ff-el-image-input-src' for='verletzung_02aa1b9dd21ed6cea7ed824457c2d4d6' aria-label='Schwer verletzt'><\/label><label class='ff-el-form-check-label' for='verletzung_02aa1b9dd21ed6cea7ed824457c2d4d6'><input  type=\"radio\" name=\"verletzung\" data-name=\"verletzung\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"schwer_verletzt\"  id='verletzung_02aa1b9dd21ed6cea7ed824457c2d4d6' aria-label='Schwer verletzt' aria-invalid='false' aria-required=true> <span>Schwer verletzt<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.online\/wp-content\/uploads\/2021\/10\/nein.svg)' class='ff-el-image-input-src' for='verletzung_33786204f7b5874c4b3e7a8004923a05' aria-label='Nicht verletzt'><\/label><label class='ff-el-form-check-label' for='verletzung_33786204f7b5874c4b3e7a8004923a05'><input  type=\"radio\" name=\"verletzung\" data-name=\"verletzung\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"nicht_verletzt\"  id='verletzung_33786204f7b5874c4b3e7a8004923a05' aria-label='Nicht verletzt' aria-invalid='false' aria-required=true> <span>Nicht verletzt<\/span><\/label><\/div><\/div><\/div><\/div><div class='step-nav ff_step_nav_last'><button style='float: left;'  type='button' data-action='prev' class='ff-btn ff-btn-prev ff-btn-secondary' aria-label='Vorherige'>Vorherige<\/button><button style='float: right;'  type='button' data-action='next' class='ff-float-right ff-btn ff-btn-next ff-btn-secondary' aria-label='N\u00e4chste Seite'>N\u00e4chste Seite<\/button><\/div><\/div><div style='display: none;' class=\" fluentform-step\" data-name=\"form_step-5_2\" ><div class='ff-el-group choose_ff1 ff_list_buttons'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label   aria-label=\"Welche Rolle haben Sie an dem Unfall?\">Welche Rolle haben Sie an dem Unfall?<\/label><\/div><div class='ff-el-input--content'><div class=\"ff_el_checkable_photo_holders\"><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.online\/wp-content\/uploads\/2021\/10\/geschaedigter.svg)' class='ff-el-image-input-src' for='rolle_919cba41d645095bbc74b8c85026a33f' aria-label='Gesch\u00e4digter'><\/label><label class='ff-el-form-check-label' for='rolle_919cba41d645095bbc74b8c85026a33f'><input  type=\"radio\" name=\"rolle\" data-name=\"rolle\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"geschaedigter\"  id='rolle_919cba41d645095bbc74b8c85026a33f' aria-label='Gesch\u00e4digter' aria-invalid='false' aria-required=true> <span>Gesch\u00e4digter<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.online\/wp-content\/uploads\/2021\/10\/verursacher.svg)' class='ff-el-image-input-src' for='rolle_babaec9b122195f24ae13f940f37647b' aria-label='Verursacher'><\/label><label class='ff-el-form-check-label' for='rolle_babaec9b122195f24ae13f940f37647b'><input  type=\"radio\" name=\"rolle\" data-name=\"rolle\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"verursacher\"  id='rolle_babaec9b122195f24ae13f940f37647b' aria-label='Verursacher' aria-invalid='false' aria-required=true> <span>Verursacher<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.online\/wp-content\/uploads\/2021\/10\/teilschuld.svg)' class='ff-el-image-input-src' for='rolle_24056b7c22911b37c9e3d7e58cf3816f' aria-label='Teilschuld'><\/label><label class='ff-el-form-check-label' for='rolle_24056b7c22911b37c9e3d7e58cf3816f'><input  type=\"radio\" name=\"rolle\" data-name=\"rolle\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"teilschuld\"  id='rolle_24056b7c22911b37c9e3d7e58cf3816f' aria-label='Teilschuld' aria-invalid='false' aria-required=true> <span>Teilschuld<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.online\/wp-content\/uploads\/2021\/10\/fragezeichen.svg)' class='ff-el-image-input-src' for='rolle_82e14e8671270f9f179dc11504d21a2d' aria-label='Nicht gekl\u00e4rt'><\/label><label class='ff-el-form-check-label' for='rolle_82e14e8671270f9f179dc11504d21a2d'><input  type=\"radio\" name=\"rolle\" data-name=\"rolle\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"nicht_geklaert\"  id='rolle_82e14e8671270f9f179dc11504d21a2d' aria-label='Nicht gekl\u00e4rt' aria-invalid='false' aria-required=true> <span>Nicht gekl\u00e4rt<\/span><\/label><\/div><\/div><\/div><\/div><div class='step-nav ff_step_nav_last'><button style='float: left;'  type='button' data-action='prev' class='ff-btn ff-btn-prev ff-btn-secondary' aria-label='Vorherige'>Vorherige<\/button><button style='float: right;'  type='button' data-action='next' class='ff-float-right ff-btn ff-btn-next ff-btn-secondary' aria-label='N\u00e4chste Seite'>N\u00e4chste Seite<\/button><\/div><\/div><div style='display: none;' class=\" fluentform-step\" data-name=\"form_step-5_3\" ><div class='ff-el-group choose_ff1 ff_list_buttons'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label   aria-label=\"Haben Sie bereits einen Anwalt beauftragt?\">Haben Sie bereits einen Anwalt beauftragt?<\/label><\/div><div class='ff-el-input--content'><div class=\"ff_el_checkable_photo_holders\"><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.online\/wp-content\/uploads\/2021\/10\/ja.svg)' class='ff-el-image-input-src' for='anwalt_a8258b3af9d8274b46df43829e918b39' aria-label='Ja'><\/label><label class='ff-el-form-check-label' for='anwalt_a8258b3af9d8274b46df43829e918b39'><input  type=\"radio\" name=\"anwalt\" data-name=\"anwalt\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"ja\"  id='anwalt_a8258b3af9d8274b46df43829e918b39' aria-label='Ja' aria-invalid='false' aria-required=true> <span>Ja <\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check- ff-el-image-holder'><label style='background-image: url(https:\/\/fairforce.online\/wp-content\/uploads\/2021\/10\/nein.svg)' class='ff-el-image-input-src' for='anwalt_24cb6a53c37fb3cf5202198085a5d1e5' aria-label='Nein'><\/label><label class='ff-el-form-check-label' for='anwalt_24cb6a53c37fb3cf5202198085a5d1e5'><input  type=\"radio\" name=\"anwalt\" data-name=\"anwalt\" class=\"ff-el-form-check-input ff-el-form-check-radio\" value=\"nein\"  id='anwalt_24cb6a53c37fb3cf5202198085a5d1e5' aria-label='Nein' aria-invalid='false' aria-required=true> <span>Nein<\/span><\/label><\/div><\/div><\/div><\/div><div class='step-nav ff_step_nav_last'><button style='float: left;'  type='button' data-action='prev' class='ff-btn ff-btn-prev ff-btn-secondary' aria-label='Vorherige'>Vorherige<\/button><button style='float: right;'  type='button' data-action='next' class='ff-float-right ff-btn ff-btn-next ff-btn-secondary' aria-label='N\u00e4chste Seite'>N\u00e4chste Seite<\/button><\/div><\/div><div style='display: none;' class=\"kontaktdaten fluentform-step\" data-name=\"form_step-5_4\" ><div class='ff-el-group  ff-custom_html' tabindex='-1' data-name=\"custom_html-5_5\" ><p style=\"text-align: center\">Wir pr\u00fcfen Ihren Schadensersatz <strong>kostenfrei<\/strong> und <strong>unverbindlich<\/strong>.<\/p><\/div><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_2 before-validation-screen'><div class='ff-t-cell ff-t-column-1' style='flex-basis: 20%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_5_salutation' id='label_ff_5_salutation' aria-label=\"Anrede\">Anrede<\/label><\/div><div class='ff-el-input--content'><select name=\"salutation\" id=\"ff_5_salutation\" class=\"ff-el-form-control ff_ff1_salutation\" data-name=\"salutation\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"true\" aria-labelledby=\"label_ff_5_salutation\"><option value=\"\">\u2013<\/option><option value=\"Herr\"  >Herr<\/option><option value=\"Frau\"  >Frau<\/option><\/select><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 80%;'><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_5_names_first_name_' id='label_ff_5_names_first_name_' >Ihr Vorname<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_5_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Vorname\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_5_names_last_name_' id='label_ff_5_names_last_name_' >Ihr Nachname<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_5_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"Nachname\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group before-validation-screen ff-phone-number'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_5_phone' id='label_ff_5_phone' aria-label=\"Telefon\">Telefon<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"+49 1234 567890\" data-name=\"phone\" id=\"ff_5_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=true><\/div><\/div><div class='ff-el-group  ff-custom_html ff1-phone-number-error before-validation-screen' tabindex='-1' data-name=\"custom_html-5_6\" ><\/div><div class='ff-el-group  before-validation-screen required-for-send-validation  ff-el-input--content'><div class='ff-el-form-check ff-el-tc'><label aria-label='Hiermit erkl\u00e4re ich meine Einwilligung zum kostenfreien R\u00fcckruf *' class='ff-el-form-check-label ff_tc_label' for=gdpr-agreement_313b4829e08e8598dd91fb875f15ae74><span class='ff_tc_checkbox'><input type=\"checkbox\" name=\"gdpr-agreement\" class=\"ff-el-form-check-input ff_gdpr_field\" data-name=\"gdpr-agreement\" id=\"gdpr-agreement_313b4829e08e8598dd91fb875f15ae74\"  value='on' aria-invalid='false' aria-required=true><\/span> <div class='ff_t_c'>Hiermit erkl\u00e4re ich meine Einwilligung zum kostenfreien R\u00fcckruf *<\/div><\/label><\/div><\/div><div class='ff-el-group  ff-custom_html ff1-sms-custom-code-container' tabindex='-1' data-name=\"custom_html-5_7\" ><\/div><input type=\"hidden\" name=\"utm_source\" data-name=\"utm_source\" ><input type=\"hidden\" name=\"utm_medium\" data-name=\"utm_medium\" ><input type=\"hidden\" name=\"utm_campaign\" data-name=\"utm_campaign\" ><input type=\"hidden\" name=\"utm_term\" data-name=\"utm_term\" ><input type=\"hidden\" name=\"utm_content\" data-name=\"utm_content\" ><input type=\"hidden\" name=\"utm_expid\" data-name=\"utm_expid\" ><input type=\"hidden\" name=\"fr_cid\" data-name=\"fr_cid\" ><input type=\"hidden\" name=\"fr_agid\" data-name=\"fr_agid\" ><input type=\"hidden\" name=\"fr_kw\" data-name=\"fr_kw\" ><input type=\"hidden\" name=\"fr_mt\" data-name=\"fr_mt\" ><input type=\"hidden\" name=\"fr_nw\" data-name=\"fr_nw\" ><input type=\"hidden\" name=\"fr_loc\" data-name=\"fr_loc\" ><input type=\"hidden\" name=\"fr_dev\" data-name=\"fr_dev\" ><input type=\"hidden\" name=\"fr_pl\" data-name=\"fr_pl\" ><input type=\"hidden\" name=\"fr_tg\" data-name=\"fr_tg\" ><input type=\"hidden\" name=\"fr_tlp\" data-name=\"fr_tlp\" ><input type=\"hidden\" name=\"source_url\" value=\"%%postUrl%%\" data-name=\"source_url\" >        <div class=\"ff-step-t-container ff-inner_submit_container ff-column-container ff_columns_total_2\">\n            <div class=\"ff-t-cell ff-t-column-1\"><div class='step-nav ff_step_nav_last'><button style='float: left;'  type='button' data-action='prev' class='ff-btn ff-btn-prev ff-btn-secondary' aria-label='Previous'>Previous<\/button><\/div><\/div>\n            <div class=\"ff-t-cell ff-t-column-2\">\n                <div class='ff-el-group ff-text-left validation-screen ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\"  aria-label=\"Jetzt unverbindlich anfragen\">Jetzt unverbindlich anfragen<\/button><\/div>            <\/div>\n        <\/div>\n        <\/div><\/div><\/div>\n        <\/fieldset><\/form><div id='fluentform_5_errors' class='ff-errors-in-stack ff_form_instance_5_1 ff-form-loading_errors ff_form_instance_5_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_5_1 = {\"id\":\"5\",\"ajaxUrl\":\"https:\\\/\\\/fairforce.one\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_5_1\",\"form_id_selector\":\"fluentform_5\",\"rules\":{\"fahrzeugtyp\":{\"required\":{\"value\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"Dieses Feld ist erforderlich\",\"global\":true}},\"verletzung\":{\"required\":{\"value\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"Dieses Feld ist erforderlich\",\"global\":true}},\"rolle\":{\"required\":{\"value\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"Dieses Feld ist erforderlich\",\"global\":true}},\"anwalt\":{\"required\":{\"value\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"Dieses Feld ist erforderlich\",\"global\":true}},\"salutation\":{\"required\":{\"value\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"Dieses Feld ist erforderlich\",\"global\":true}},\"names[first_name]\":{\"required\":{\"value\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"Dieses Feld ist erforderlich\",\"global\":true}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"Dieses Feld ist erforderlich\",\"global\":true}},\"names[last_name]\":{\"required\":{\"value\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"Dieses Feld ist erforderlich\",\"global\":true}},\"phone\":{\"required\":{\"value\":true,\"global\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"Dieses Feld ist erforderlich\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Phone number is not valid\",\"global_message\":\"Phone number is not valid\"}},\"gdpr-agreement\":{\"required\":{\"value\":true,\"message\":\"Ohne Zustimmung d\\u00fcrfen wir Sie nicht kontaktieren.\",\"global_message\":\"Dieses Feld ist erforderlich\",\"global\":false}}},\"debounce_time\":300,\"file_upload_settings\":[]};\n                            <\/script>\n                        <\/div>\n\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1903474 elementor-widget elementor-widget-template\" data-id=\"1903474\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"8541\" class=\"elementor elementor-8541\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-09d08cd e-flex e-con-boxed e-con e-parent\" data-id=\"09d08cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3824aa6 elementor-widget__width-auto elementor-widget elementor-widget-html\" data-id=\"3824aa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- TrustBox widget - Mini -->\r\n<div style=\"max-width:150px;  max-height:100px;\" class=\"trustpilot-widget\" data-locale=\"de-DE\" data-template-id=\"53aa8807dec7e10d38f59f32\" data-businessunit-id=\"62e24615a2e26dceb7ec70ab\" data-style-height=\"150px\" data-style-width=\"100%\" data-theme=\"light\">\r\n  <a href=\"https:\/\/de.trustpilot.com\/review\/fairforce.one\" target=\"_blank\" rel=\"noopener\">Trustpilot<\/a>\r\n<\/div>\r\n<!-- End TrustBox widget -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be179d0 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"be179d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tms-icert.tuvsud.com\/services\/erl\/(S(21vckead4a5hhl4soxauhix0))\/erl_result.aspx?cert_id=&#038;comb1=&#038;CompName=fairforce.one&#038;Country=&#038;cScope1=&#038;md_id=3&#038;page_lang=de\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"298\" height=\"298\" src=\"https:\/\/fairforce.one\/wp-content\/uploads\/2021\/10\/ISO_9001_farbe_single.png\" class=\" attachment-medium size-medium wp-image-307\" alt=\"T\u00dcV S\u00dcD Zertifizierungssiegel f\u00fcr ISO 9001 in Farbe, Qualit\u00e4tsnachweis\" srcset=\"https:\/\/fairforce.one\/wp-content\/uploads\/2021\/10\/ISO_9001_farbe_single.png 298w, https:\/\/fairforce.one\/wp-content\/uploads\/2021\/10\/ISO_9001_farbe_single-150x150.png 150w\" sizes=\"(max-width: 298px) 100vw, 298px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da4658b elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"da4658b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"226\" height=\"97\" src=\"https:\/\/fairforce.one\/wp-content\/uploads\/2022\/03\/Asset-1.svg\" class=\" attachment-medium size-medium wp-image-8404\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f684b8 e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"3f684b8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3245ae2 elementor-widget elementor-widget-template\" data-id=\"3245ae2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"8554\" class=\"elementor elementor-8554\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-b00aa0e e-con-full e-flex e-con e-parent\" data-id=\"b00aa0e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5544740 elementor-view-framed elementor-mobile-position-inline-start elementor-shape-circle elementor-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5544740\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 30.38 91\"><path d=\"M61.13,33.16h-.28L45,41.7l-2.38-9.38L62.53,21.68H73v91H61.13Z\" transform=\"translate(-42.65 -21.68)\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMit nur 6 Klicks stellen Sie \nuns hier Ihre Anfrage \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26470b2 elementor-view-framed elementor-mobile-position-inline-start elementor-shape-circle elementor-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"26470b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 58.1 92.54\"><path d=\"M34.39,112.68v-7.56l9.66-9.38c23.24-22.12,33.74-33.88,33.88-47.6,0-9.24-4.48-17.78-18.06-17.78-8.26,0-15.12,4.2-19.32,7.7l-3.92-8.68a39.93,39.93,0,0,1,25.76-9.24c19.6,0,27.86,13.44,27.86,26.46,0,16.8-12.18,30.38-31.36,48.86l-7.28,6.72v.28H92.49v10.22Z\" transform=\"translate(-34.39 -20.14)\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEin Verkehrsrecht-Spezialist mit top-Bewertung ruft Sie an. \nSie besprechen direkt Ihr Anliegen und erhalten Rat. <br><strong>Garantiert kostenfrei und unverbindlich! <\/strong>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a512d7a elementor-view-framed elementor-mobile-position-inline-start elementor-shape-circle elementor-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a512d7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 56.84 94.08\"><path d=\"M37.33,98.54a41.18,41.18,0,0,0,20.16,5.74c15.82,0,20.72-10.08,20.58-17.64-.14-12.74-11.62-18.2-23.52-18.2H47.69V59.2h6.86c9,0,20.3-4.62,20.3-15.4,0-7.28-4.62-13.72-16-13.72a33.42,33.42,0,0,0-18.2,6l-3.22-9c4.76-3.5,14-7,23.8-7,17.92,0,26,10.64,26,21.7,0,9.38-5.6,17.36-16.8,21.42v.28c11.2,2.24,20.3,10.64,20.3,23.38,0,14.56-11.34,27.3-33.18,27.3-10.22,0-19.18-3.22-23.66-6.16Z\" transform=\"translate(-33.97 -20.14)\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir sollen helfen? \nIhr Auftrag kommt direkt aufs Handy. <br>\n<strong>Einfach &amp; sicher<\/strong>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-815c9c0 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"815c9c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"#ablauf\"><span style=\"text-decoration: underline;\">Der Ablauf im Detail &gt;<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a4c0cf elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"3a4c0cf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a4c3690 e-con-full e-grid e-con e-child\" data-id=\"a4c3690\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-30572b5 e-flex e-con-boxed e-con e-child\" data-id=\"30572b5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f22cdd elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7f22cdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-shield-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">kostenfreie Beratung <br>rechtssichere Unfallmeldung <br>schnell wieder mobil <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f8dd976 e-flex e-con-boxed e-con e-child\" data-id=\"f8dd976\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd38e67 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bd38e67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-shield-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">fairforce koordiniert<br> <strong>Mietwagen, Gutachten, Werkstatt, alle Versicherungen<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8066d78 e-flex e-con-boxed e-con e-child\" data-id=\"8066d78\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6de912a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6de912a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-shield-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">bew\u00e4hrte Pr\u00fcfung, Durchsetzung und Auszahlung aller Schadenersatz-Arten<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2bce158 e-flex e-con-boxed e-con e-child\" data-id=\"2bce158\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-406cf00 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"406cf00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Durchschnittlich <strong>plus 480 \u20ac<\/strong> Mehrauszahlung f\u00fcr <span class=\"ff1-nowrap\">Sie <sup><a href=\"#footnotes\">2<\/a><\/sup><\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-460e2c5 e-flex e-con-boxed e-con e-child\" data-id=\"460e2c5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d18ef1 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8d18ef1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mehr als <b>104 Mio. \u20ac<\/b> Schadensersatz f\u00fcr Kunden erwirkt<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c24b8e1 e-flex e-con-boxed e-con e-child\" data-id=\"c24b8e1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-045ec89 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"045ec89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2024 Deutschlands <strong>bestbewertete<\/strong>  <span class=\"ff1-nowrap\">Unfallplattform <sup><a href=\"#footnotes\">1<\/a><\/sup><\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5837250 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5837250\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30bbcd0\" data-id=\"30bbcd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f2b9e3 elementor-widget elementor-widget-template\" data-id=\"8f2b9e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"7774\" class=\"elementor elementor-7774\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-06f4437 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"06f4437\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0df1f49 e-con-full e-flex e-con e-child\" data-id=\"0df1f49\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a1cf275 e-flex e-con-boxed e-con e-child\" data-id=\"a1cf275\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-785a45a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"785a45a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-thumbs-up\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2025 Deutschlands <strong>bestbewertete<\/strong>  <span class=\"ff1-nowrap\">Unfallplattform <sup><a href=\"#footnotes\">1<\/a><\/sup><\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d9c998 e-flex e-con-boxed e-con e-child\" data-id=\"1d9c998\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa7c5b3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"fa7c5b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-sort-amount-up\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Durchschnittlich <strong>plus 480 \u20ac<\/strong> Mehrauszahlung f\u00fcr <span class=\"ff1-nowrap\">Sie <sup><a href=\"#footnotes\">2<\/a><\/sup><\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f1ca062 e-flex e-con-boxed e-con e-child\" data-id=\"f1ca062\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbb6278 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"cbb6278\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-money-bill-wave\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mehr als <b>116 Mio. \u20ac<\/b> Schadensersatz f\u00fcr Kunden erwirkt<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bed3f8 e-flex e-con-boxed e-con e-parent\" data-id=\"3bed3f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-adf414c e-con-full e-flex e-con e-child\" data-id=\"adf414c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1aace31 elementor-widget elementor-widget-heading\" data-id=\"1aace31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><small>Ihr pers\u00f6nlicher<\/small><br>Unfall-Concierge<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed3e64b elementor-widget elementor-widget-text-editor\" data-id=\"ed3e64b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gutachter nach Hause, Mietwagen an den Arbeitsplatz, Lieblingswerkstatt reservieren, Abrechnung mit Versicherung, anwaltliche Absicherung im Hintergrund \u2026\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bef66c9 elementor-widget elementor-widget-heading\" data-id=\"bef66c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Wir denken an alles. Wir retten Ihre Zeit.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de5d8f1 elementor-widget elementor-widget-text-editor\" data-id=\"de5d8f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00dcber unser cloudbasiertes Servicecenter in Leipzig organisieren wir die faire Regulierung Ihres Unfalls von der Meldung bis zum Abschluss.<\/p><p>Als digital organisiertes Spezialistennetzwerk erschlie\u00dfen wir unseren Kunden eine neue Qualit\u00e4t der Schadensregulierung.<\/p><p><span style=\"font-weight: 400;\"><strong>Den Fortschritt Ihrer Unfallregulierung k\u00f6nnen Sie dabei jederzeit \u00fcber unser innovatives KIS (Kunden-Informations-System)\u00a0verfolgen<\/strong> \u2013 m\u00fcssen Sie aber nicht ;-).<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0aa426d elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"0aa426d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-chevron-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt Unfall melden <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37e5d32 e-con-full e-flex e-con e-child\" data-id=\"37e5d32\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0197aa7 e-con-full e-flex e-con e-child\" data-id=\"0197aa7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-84b8942 e-con-full e-flex e-con e-child\" data-id=\"84b8942\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ef6039 elementor-widget elementor-widget-image\" data-id=\"8ef6039\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"99\" height=\"99\" src=\"https:\/\/fairforce.one\/wp-content\/uploads\/2022\/01\/ff1_logo_Bildmarke_WEISS.svg\" class=\" attachment-large size-large wp-image-18342\" alt=\"Wei\u00dfes fairforce.one Logo mit stilisiertem Elefanten und Schriftzug f\u00fcr dunklen Hintergrund\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9262da3 elementor-widget elementor-widget-heading\" data-id=\"9262da3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><small>ein Angebot der<\/small><br>\nfairforce Group<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-237e94f elementor-widget elementor-widget-heading\" data-id=\"237e94f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Wei\u00dfenfelser Str. 65J |  04229 Leipzig<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21f36c8 elementor-widget elementor-widget-heading\" data-id=\"21f36c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Die Pioniere f\u00fcr smarte Schadensregulierung <br>seit 2017\n\n<!--- Ihr Netzwerk f\u00fcr professionelle Schadensregulierung.\n--><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f20e0d elementor-widget elementor-widget-html\" data-id=\"2f20e0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- TrustBox widget - Starter -->\r\n<div class=\"trustpilot-widget\" data-locale=\"de-DE\" data-template-id=\"5613c9cde69ddc09340c6beb\" data-businessunit-id=\"62e24615a2e26dceb7ec70ab\" data-style-height=\"100%\" data-style-width=\"100%\" data-theme=\"light\">\r\n  <a href=\"https:\/\/de.trustpilot.com\/review\/fairforce.one\" target=\"_blank\" rel=\"noopener\">Trustpilot<\/a>\r\n<\/div>\r\n<!-- End TrustBox widget -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e6c7c2 e-flex e-con-boxed e-con e-parent\" data-id=\"0e6c7c2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9d21c1a e-con-full e-flex e-con e-child\" data-id=\"9d21c1a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21f0db6 elementor-widget elementor-widget-heading\" data-id=\"21f0db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"so-einfach-funktionierts\" title=\"So einfach funktioniert's:\">So einfach funktioniert's:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-755de13 elementor-pagination-type-bullets elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"755de13\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Einfache Meldung&quot;,&quot;_id&quot;:&quot;9ec97a6&quot;},{&quot;slide_title&quot;:&quot;Kostenfreie Pr\\u00fcfung&quot;,&quot;_id&quot;:&quot;e40b758&quot;},{&quot;slide_title&quot;:&quot;Klarheit und Durchsetzung&quot;,&quot;_id&quot;:&quot;96eee9d&quot;}],&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;offset_sides&quot;:&quot;both&quot;,&quot;offset_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;offset_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"So einfach funktioniert die Unfallmeldung\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd3e8f9 e-con-full e-flex e-con e-child\" data-id=\"fd3e8f9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36ed76a elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"36ed76a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fad fa-check-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-316469d elementor-widget elementor-widget-heading\" data-id=\"316469d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"einfache-meldung\" title=\"Einfache Meldung\">Einfache Meldung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37f60e6 elementor-widget elementor-widget-text-editor\" data-id=\"37f60e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sie klicken Ihren Unfall einfach und bequem hier auf der Startseite durch, oder Sie w\u00e4hlen unsere kostenfreie Hotline <a href=\"tel:08003011160\"> 0800 \u2013 30 111 60<\/a>.<\/p><p>Beide Wege sind <strong>v\u00f6llig unverbindlich<\/strong> und in wenigen Minuten erledigt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-159c6b3 e-con-full e-flex e-con e-child\" data-id=\"159c6b3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e3fd7f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4e3fd7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fad fa-search\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb84fb8 elementor-widget elementor-widget-heading\" data-id=\"bb84fb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"kostenfreie-pruefung\" title=\"Kostenfreie Pr\u00fcfung\">Kostenfreie Pr\u00fcfung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17fc13c elementor-widget elementor-widget-text-editor\" data-id=\"17fc13c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Binnen 3 Minuten<sup><a href=\"#footnotes\">3<\/a><\/sup> kontaktiert Sie ein Spezialist der fairforce.one. Unsere Experten bewerten pers\u00f6nlich und individuell Ihren Fall und die f\u00fcr Sie besten n\u00e4chsten Schritte. <strong>Garantiert kostenfrei!<\/strong><\/p><p>Wenn Sie sich f\u00fcr uns entscheiden, bekommen Sie Ihren pers\u00f6nlichen Auftrag direkt und sicher auf Ihr Smartphone.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9f9baa e-con-full e-flex e-con e-child\" data-id=\"b9f9baa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-896b4bc elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"896b4bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fad fa-lightbulb-on\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffd5165 elementor-widget elementor-widget-heading\" data-id=\"ffd5165\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"klarheit-durchsetzung\" title=\"Klarheit &amp; Durchsetzung\">Klarheit &amp; Durchsetzung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67ca922 elementor-widget elementor-widget-text-editor\" data-id=\"67ca922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sie erhalten binnen 24h<sup><a href=\"#footnotes\">3<\/a><\/sup> eine anwaltliche Bewertung auf Ihr Smartphone. Ihre Werkstatt und Ihr Gutachter werden eingebunden oder wir vermitteln Ihnen gepr\u00fcfte Spezialisten.<\/p><p>Die Durchsetzung Ihrer Schadenersatzanspr\u00fcche hat bereits begonnen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfe0790 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"cfe0790\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-chevron-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt Unfall melden <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b4b037 e-flex e-con-boxed e-con e-parent\" data-id=\"9b4b037\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0cba073 e-con-full e-flex e-con e-child\" data-id=\"0cba073\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b019bf3 elementor-icon-list--layout-inline elementor-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b019bf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nutzungsausfall<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Orgapauschale<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Herstellergerechte Reparatur<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ad\u00e4quater Mietwagen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Heilbehandlungskosten<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Abschleppkosten<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Entgangener Urlaub<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fahrtkostenersatz<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Haushaltsf\u00fchrungshilfe<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">KFZ-An- und Abmeldung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pers\u00f6nlicher Sachschaden<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Schmerzensgeld<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Standgeb\u00fchren<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Unabh\u00e4ngiger Gutachter<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Verdienstausfall<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wertminderung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eadb475 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"eadb475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!--<script>\/\/ Sequential scale animation for list items (in random order)\r\n  const items = document.querySelectorAll('#animated-list .elementor-icon-list-item');\r\n    const duration = 800; \/\/ Duration for each scale up\/down in milliseconds\r\n  const delay = 700; \/\/ Delay between each item animation\r\n\r\nfunction animateListItems() {\r\n  \r\n  if (items.length === 0) {\r\n    console.warn('No items found with selector \"#animated-list .elementor-icon-list-item\"');\r\n    return;\r\n  }\r\n  \r\n  \/\/ Animation configuration\r\n  const scaleTo = 1.1; \/\/ Scale up to 120%\r\n\r\n  \r\n  \/\/ Reset all items to original scale first\r\n  items.forEach(item => {\r\n    item.style.transform = 'scale(1)';\r\n    item.style.transition = `transform ${duration}ms ease-in-out`;\r\n  });\r\n  \r\n  \/\/ Create randomized order array\r\n  const randomOrder = Array.from({ length: items.length }, (_, i) => i)\r\n    .sort(() => Math.random() - 0.5);\r\n  \r\n  \/\/ Animate each item in random order\r\n  randomOrder.forEach((itemIndex, animationIndex) => {\r\n    const item = items[itemIndex];\r\n    \r\n    setTimeout(() => {\r\n      \/\/ Scale up\r\n      item.style.transform = `scale(${scaleTo})`;\r\n      \r\n      \/\/ Scale back down after the duration\r\n      setTimeout(() => {\r\n        item.style.transform = 'scale(1)';\r\n      }, duration);\r\n      \r\n    }, animationIndex * (duration + delay));\r\n  });\r\n  \r\n  return items;\r\n}\r\n\r\n\/\/ Function to start the animation with optional loop\r\nfunction startAnimation(loop = false, loopDelay = 2000) {\r\n    \r\n      animateListItems()\r\n      \r\n  if (loop) {\r\n    const totalDuration = items.length * (duration + delay) + 300; \/\/ Total time for all animations\r\n    setInterval(animateListItems, totalDuration + loopDelay);\r\n  } \r\n}\r\n\r\n\/\/ Auto-start when DOM is ready\r\nif (document.readyState === 'loading') {\r\n  document.addEventListener('DOMContentLoaded', () => startAnimation(true, 1000)\r\n  );\r\n}\r\n\r\n\/\/ Export functions for manual control\r\nwindow.animateListItems = animateListItems;\r\nwindow.startAnimation = startAnimation;\r\n<\/script>--->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b754d24 elementor-widget elementor-widget-heading\" data-id=\"b754d24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"warum-fairforce-one\" title=\"Warum fairforce.one?\">Warum fairforce.one?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1db6685 elementor-pagination-type-bullets elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"1db6685\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Mehr Leistung&quot;,&quot;_id&quot;:&quot;9ec97a6&quot;},{&quot;_id&quot;:&quot;c288846&quot;,&quot;slide_title&quot;:&quot;Mehr Klarheit&quot;},{&quot;_id&quot;:&quot;e123b43&quot;,&quot;slide_title&quot;:&quot;Mehr Lebenszeit&quot;}],&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;offset_sides&quot;:&quot;both&quot;,&quot;offset_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;offset_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Warum fairforce.one?\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28eca77 e-con-full e-flex e-con e-child\" data-id=\"28eca77\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-f6fd9d9 e-flex e-con-boxed e-con e-child\" data-id=\"f6fd9d9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fae2894 elementor-widget elementor-widget-heading\" data-id=\"fae2894\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><strong>16<\/strong><small>Anspruchsarten<\/small><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be31c35 elementor-widget__width-initial elementor-widget elementor-widget-html\" data-id=\"be31c35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"marquee-container\">\r\n  <div class=\"marquee-track\">\r\n    <span>Nutzungsausfall<\/span>\r\n    <span>Orgapauschale<\/span>\r\n    <span>Herstellergerechte Reparatur<\/span>\r\n    <span>Ad\u00e4quater Mietwagen<\/span>\r\n    <span>Heilbehandlungskosten<\/span>\r\n    <span>Abschleppkosten<\/span>\r\n    <span>Entgangener Urlaub<\/span>\r\n    <span>Fahrtkostenersatz<\/span>\r\n    <span>Haushaltsf\u00fchrungshilfe<\/span>\r\n    <span>KFZ-An- und Abmeldung<\/span>\r\n    <span>Pers\u00f6nlicher Sachschaden<\/span>\r\n    <span>Schmerzensgeld<\/span>\r\n    <span>Standgeb\u00fchren<\/span>\r\n    <span>Unabh\u00e4ngiger Gutachter<\/span>\r\n    <span>Verdienstausfall<\/span>\r\n    <span>Wertminderung<\/span>\r\n\r\n    <!-- Duplicate for seamless scroll -->\r\n    <span>Nutzungsausfall<\/span>\r\n    <span>Orgapauschale<\/span>\r\n    <span>Herstellergerechte Reparatur<\/span>\r\n    <span>Ad\u00e4quater Mietwagen<\/span>\r\n    <span>Heilbehandlungskosten<\/span>\r\n    <span>Abschleppkosten<\/span>\r\n    <span>Entgangener Urlaub<\/span>\r\n    <span>Fahrtkostenersatz<\/span>\r\n    <span>Haushaltsf\u00fchrungshilfe<\/span>\r\n    <span>KFZ-An- und Abmeldung<\/span>\r\n    <span>Pers\u00f6nlicher Sachschaden<\/span>\r\n    <span>Schmerzensgeld<\/span>\r\n    <span>Standgeb\u00fchren<\/span>\r\n    <span>Unabh\u00e4ngiger Gutachter<\/span>\r\n    <span>Verdienstausfall<\/span>\r\n    <span>Wertminderung<\/span>\r\n  <\/div>\r\n<\/div>\r\n<div class=\"marquee-container\">\r\n  <div class=\"marquee-track\">\r\n    <span>Haushaltsf\u00fchrungshilfe<\/span>\r\n    <span>KFZ-An- und Abmeldung<\/span>\r\n    <span>Pers\u00f6nlicher Sachschaden<\/span>\r\n    <span>Schmerzensgeld<\/span>\r\n    <span>Standgeb\u00fchren<\/span>\r\n    <span>Unabh\u00e4ngiger Gutachter<\/span>\r\n    <span>Verdienstausfall<\/span>\r\n    <span>Wertminderung<\/span>\r\n    <span>Nutzungsausfall<\/span>\r\n    <span>Orgapauschale<\/span>\r\n    <span>Herstellergerechte Reparatur<\/span>\r\n    <span>Ad\u00e4quater Mietwagen<\/span>\r\n    <span>Heilbehandlungskosten<\/span>\r\n    <span>Abschleppkosten<\/span>\r\n    <span>Entgangener Urlaub<\/span>\r\n    <span>Fahrtkostenersatz<\/span>\r\n\r\n    <!-- Duplicate for seamless scroll -->\r\n    <span>Haushaltsf\u00fchrungshilfe<\/span>\r\n    <span>KFZ-An- und Abmeldung<\/span>\r\n    <span>Pers\u00f6nlicher Sachschaden<\/span>\r\n    <span>Schmerzensgeld<\/span>\r\n    <span>Standgeb\u00fchren<\/span>\r\n    <span>Unabh\u00e4ngiger Gutachter<\/span>\r\n    <span>Verdienstausfall<\/span>\r\n    <span>Wertminderung<\/span>\r\n    <span>Nutzungsausfall<\/span>\r\n    <span>Orgapauschale<\/span>\r\n    <span>Herstellergerechte Reparatur<\/span>\r\n    <span>Ad\u00e4quater Mietwagen<\/span>\r\n    <span>Heilbehandlungskosten<\/span>\r\n    <span>Abschleppkosten<\/span>\r\n    <span>Entgangener Urlaub<\/span>\r\n    <span>Fahrtkostenersatz<\/span>\r\n  <\/div>\r\n<\/div>\r\n<div class=\"marquee-container\">\r\n  <div class=\"marquee-track\">\r\n    <span>Standgeb\u00fchren<\/span>\r\n    <span>Ad\u00e4quater Mietwagen<\/span>\r\n    <span>Heilbehandlungskosten<\/span>\r\n    <span>Abschleppkosten<\/span>\r\n    <span>Entgangener Urlaub<\/span>\r\n    <span>Fahrtkostenersatz<\/span>\r\n    <span>Haushaltsf\u00fchrungshilfe<\/span>\r\n    <span>KFZ-An- und Abmeldung<\/span>\r\n    <span>Pers\u00f6nlicher Sachschaden<\/span>\r\n    <span>Schmerzensgeld<\/span>\r\n    <span>Unabh\u00e4ngiger Gutachter<\/span>\r\n    <span>Verdienstausfall<\/span>\r\n    <span>Wertminderung<\/span>\r\n    <span>Nutzungsausfall<\/span>\r\n    <span>Orgapauschale<\/span>\r\n    <span>Herstellergerechte Reparatur<\/span>\r\n\r\n\r\n    <!-- Duplicate for seamless scroll -->\r\n    <span>Standgeb\u00fchren<\/span>\r\n    <span>Ad\u00e4quater Mietwagen<\/span>\r\n    <span>Heilbehandlungskosten<\/span>\r\n    <span>Abschleppkosten<\/span>\r\n    <span>Entgangener Urlaub<\/span>\r\n    <span>Fahrtkostenersatz<\/span>\r\n    <span>Haushaltsf\u00fchrungshilfe<\/span>\r\n    <span>KFZ-An- und Abmeldung<\/span>\r\n    <span>Pers\u00f6nlicher Sachschaden<\/span>\r\n    <span>Schmerzensgeld<\/span>\r\n    <span>Unabh\u00e4ngiger Gutachter<\/span>\r\n    <span>Verdienstausfall<\/span>\r\n    <span>Wertminderung<\/span>\r\n    <span>Nutzungsausfall<\/span>\r\n    <span>Orgapauschale<\/span>\r\n    <span>Herstellergerechte Reparatur<\/span>\r\n  <\/div>\r\n<\/div>\r\n<style>\r\n.marquee-container {\r\n    margin-bottom: 5px;\r\n  overflow: hidden;\r\n  white-space: nowrap;\r\n  width: 100%;\r\n  background: transparent;\r\n  position: relative;\r\n              -webkit-mask: linear-gradient(to right, transparent 0%, white 15%, white 85%, transparent 100%);\r\n            mask: linear-gradient(to right, transparent 0%, white 15%, white 85%, transparent 100%);\r\n}\r\n\r\n.marquee-container:after {\r\n    left: auto;\r\n    right: 0;\r\n        background: linear-gradient(0.75turn, #2d644a, transparent);\r\n}\r\n\r\n.marquee-track {\r\n  display: inline-flex;\r\n  animation: scroll-left 120s linear infinite;\r\n  gap: 5px;\r\n}\r\n\r\n.marquee-track span {\r\n  display: inline-block;\r\n  padding: .2rem .7rem .3rem .7rem;\r\n  font-size: 0.9rem;\r\n  line-height: 1rem;\r\n  white-space: nowrap;\r\n  flex-shrink: 0;\r\n  color: #888;\r\n  background: #f5f5f5;\r\n  border-radius: 50px;\r\n}\r\n\r\n@keyframes scroll-left {\r\n  0% {\r\n    transform: translateX(0%);\r\n  }\r\n  100% {\r\n    transform: translateX(-50%);\r\n  }\r\n}\r\n<\/style>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-785f1c6 elementor-widget elementor-widget-heading\" data-id=\"785f1c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"mehr-leistung\" title=\"Mehr Leistung\">Mehr Leistung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66377fc elementor-widget elementor-widget-text-editor\" data-id=\"66377fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Durch unsere Zulassung als Rechtsdienstleister k\u00f6nnen <\/strong><strong>wir f\u00fcr jeden Gesch\u00e4digten alle 16 Anspruchsarten pr\u00fcfen. <\/strong><\/p><p>So erhalten Sie wirklich alles, was Ihnen zusteht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-168370d e-con-full e-flex e-con e-child\" data-id=\"168370d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ca8b8c elementor-widget elementor-widget-image\" data-id=\"7ca8b8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"730\" src=\"https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/250612_phone_blob_hand_2-768x730.png\" class=\" attachment-medium_large size-medium_large wp-image-17137\" alt=\"Flache Illustration einer Hand, die ein Smartphone h\u00e4lt, vor gr\u00fcner Blob-Fl\u00e4che im fairforce.one Markendesign\" srcset=\"https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/250612_phone_blob_hand_2-768x730.png 768w, https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/250612_phone_blob_hand_2-300x285.png 300w, https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/250612_phone_blob_hand_2-1024x973.png 1024w, https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/250612_phone_blob_hand_2-13x12.png 13w, https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/250612_phone_blob_hand_2.png 1438w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e32eb52 elementor-widget elementor-widget-heading\" data-id=\"e32eb52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"mehr-klarheit\" title=\"Mehr Klarheit\">Mehr Klarheit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-534bee3 elementor-widget elementor-widget-text-editor\" data-id=\"534bee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u00dcber Ihr Smartphone sind Sie jederzeit top informiert \u2013 ganz ohne App-Download!<\/strong><\/p><p>Fortschritt, Dokumente, Auszahlungsbetr\u00e4ge \u2013 unsere Kunden lieben diese klare \u00dcbersicht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2e0ae8 e-con-full e-flex e-con e-child\" data-id=\"f2e0ae8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e85ddf8 elementor-widget elementor-widget-image\" data-id=\"e85ddf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"730\" src=\"https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/woman_blob-768x730.png\" class=\" attachment-medium_large size-medium_large wp-image-17145\" alt=\"Flache Illustration einer l\u00e4chelnden Frau vor gr\u00fcner Blob-Fl\u00e4che im fairforce.one Markendesign\" srcset=\"https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/woman_blob-768x730.png 768w, https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/woman_blob-300x285.png 300w, https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/woman_blob-1024x973.png 1024w, https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/woman_blob-13x12.png 13w, https:\/\/fairforce.one\/wp-content\/uploads\/2025\/06\/woman_blob.png 1438w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acd44b0 elementor-widget elementor-widget-heading\" data-id=\"acd44b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"mehr-lebenszeit\" title=\"Mehr Lebenszeit\">Mehr Lebenszeit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2d273b elementor-widget elementor-widget-text-editor\" data-id=\"e2d273b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Sie k\u00f6nnen sich w\u00e4hrend der Regulierung Ihres Unfalls entspannt zur\u00fccklehnen. <\/b><\/p><p>Wir k\u00fcmmern uns um den Papierkram \u2013 und Sie sind schnell wieder mobil.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2044861 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2044861\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb28265 e-con-full e-flex e-con e-child\" data-id=\"cb28265\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-21b2039 e-con-full e-flex e-con e-child\" data-id=\"21b2039\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdfea62 elementor-widget elementor-widget-heading\" data-id=\"fdfea62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"das-sagen-unsere-kunden\" title=\"Das sagen unsere Kunden:\">Das sagen unsere Kunden:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ba0170 elementor-widget elementor-widget-html\" data-id=\"5ba0170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- TrustBox widget - Grid -->\r\n<div class=\"trustpilot-widget\" data-locale=\"de-DE\" data-template-id=\"539adbd6dec7e10e686debee\" data-businessunit-id=\"62e24615a2e26dceb7ec70ab\" data-style-height=\"500px\" data-style-width=\"100%\" data-theme=\"light\" data-stars=\"4,5\" data-review-languages=\"de\">\r\n  <a href=\"https:\/\/de.trustpilot.com\/review\/fairforce.one\" target=\"_blank\" rel=\"noopener\">Trustpilot<\/a>\r\n<\/div>\r\n<!-- End TrustBox widget -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9f416b elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9f416b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;arrow&quot;,&quot;shape_divider_top_negative&quot;:&quot;yes&quot;,&quot;shape_divider_bottom&quot;:&quot;arrow&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M360 0L350 9.9 340 0 0 0 0 10 700 10 700 0\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M360 0L350 9.9 340 0 0 0 0 10 700 10 700 0\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-110c5cb\" data-id=\"110c5cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-723673b elementor-widget elementor-widget-heading\" data-id=\"723673b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"unfallregulierung-im-vergleich\" title=\"Unfallregulierung im Vergleich\">Unfallregulierung im Vergleich<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d54e6f6 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"d54e6f6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ea808a9\" data-id=\"ea808a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c81895e elementor-widget elementor-widget-price-table\" data-id=\"c81895e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"price-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-price-table\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__header\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-price-table__heading\" id=\"werkstatt-oder-gutachter\" title=\"\n\t\t\t\t\t\tWerkstatt oder Gutachter\t\t\t\t\t\t\">\n\t\t\t\t\t\tWerkstatt oder Gutachter\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__subheading\">\n\t\t\t\t\t\t\tAnspr\u00fcche werden nicht vollst\u00e4ndig ber\u00fccksichtigt.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"elementor-price-table__price\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<ul class=\"elementor-price-table__features-list\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-357e876\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-badge-check\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tKompetenz zum KFZ\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-a1ead50\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-times-octagon\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tkeine Abwehr falscher Schuldzuweisung\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-096a769\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-times-octagon\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tSchmerzensgeld und pers\u00f6nliche Anspr\u00fcche unber\u00fccksichtigt\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-e001232\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-times-octagon\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tKeine Echtzeitinformation\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-358ef42\" data-id=\"358ef42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31ac559 elementor-widget elementor-widget-price-table\" data-id=\"31ac559\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"price-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-price-table\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__header\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-price-table__heading\" id=\"fairforce-one\" title=\"\n\t\t\t\t\t\tfairforce.one\t\t\t\t\t\t\">\n\t\t\t\t\t\tfairforce.one\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__subheading\">\n\t\t\t\t\t\t\tWir denken an alles.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"elementor-price-table__price\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<ul class=\"elementor-price-table__features-list\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-357e876\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-badge-check\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tZeitaufwand: gering\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-9450c26\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-badge-check\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tAbwehr ungerechtfertigter Schuldzuweisungen &amp; Bu\u00dfgelder\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-d0e245c\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-badge-check\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tpers\u00f6nliche Unterst\u00fctzung\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-1e23039\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-badge-check\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tKlarheit \u00fcber bestehende Anspr\u00fcche\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-fef50bd\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-badge-check\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tZugang zu Expertennetzwerk\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-6cf9ce1\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-badge-check\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\terh\u00f6hte Auszahlung\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-1eb4201\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-badge-check\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\thohe Planungssicherheit\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-7cdd74e\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-badge-check\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tIhre Wunschwerkstatt, Ihr Wunschgutachter\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-685036b\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-badge-check\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tEchtzeitinformation \u00fcber Regulierungsfortschritte\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__footer\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-price-table__button elementor-button elementor-size-lg\" href=\"#\">\n\t\t\t\t\t\t\tJetzt Anspr\u00fcche pr\u00fcfen\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-price-table__additional_info\">\n\t\t\t\t\t\t\tkostenlos und unverbindlich\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b994337\" data-id=\"b994337\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd498aa elementor-widget elementor-widget-price-table\" data-id=\"dd498aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"price-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-price-table\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__header\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-price-table__heading\" id=\"auf-eigene-faust\" title=\"\n\t\t\t\t\t\tAuf eigene Faust\t\t\t\t\t\t\">\n\t\t\t\t\t\tAuf eigene Faust\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__subheading\">\n\t\t\t\t\t\t\tDu musst selbst an alles denken.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"elementor-price-table__price\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<ul class=\"elementor-price-table__features-list\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-357e876\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-times-octagon\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tVersicherung zahlt so wenig wie m\u00f6glich\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-9c4fdc3\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-times-octagon\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tZeitaufwand: Hoch\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-a1ead50\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-times-octagon\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tRisiko ungedeckter Restkosten: Hoch\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-096a769\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-times-octagon\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tGefahr falscher Schuldverteilung: Hoch\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-e001232\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-times-octagon\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tWahrscheinlichkeit unbewusster Leistungseinbu\u00dfen: extrem hoch\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1649820 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1649820\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47b3207\" data-id=\"47b3207\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f540b74 elementor-widget elementor-widget-menu-anchor\" data-id=\"f540b74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"faq\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24d2005 elementor-widget elementor-widget-menu-anchor\" data-id=\"24d2005\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"finanzierung\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26c5c27 elementor-widget elementor-widget-heading\" data-id=\"26c5c27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"haeufig-gestellte-fragen\" title=\"H\u00e4ufig gestellte Fragen\">H\u00e4ufig gestellte Fragen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8aba872 elementor-widget elementor-widget-n-accordion\" data-id=\"8aba872\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1450\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1450\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Was macht fairforce.one? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1450\" class=\"elementor-element elementor-element-6d26344 e-con-full e-flex e-con e-child\" data-id=\"6d26344\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12eea95 elementor-widget elementor-widget-text-editor\" data-id=\"12eea95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir bieten eine smarte, digitale Plattform zur vollst\u00e4ndigen und fairen Abwicklung von Unfall\u2011 und Schadensf\u00e4llen an und greifen auf ein bundesweites Netzwerk aus gepr\u00fcften Fachanw\u00e4lten, Gutachtern, Werkst\u00e4tten und Mietwagenanbietern zur\u00fcck, um wirklich all Ihre Anspr\u00fcche durchzusetzen.<\/p><p><strong>Kurz gesagt:<\/strong><br \/>Mit unserem Unfall-Concierge sind Sie nach Ihrem Unfall schnell wieder mobil \u2013 ohne Stress und viel Papierkram.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1451\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1451\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Wie finanziert sich fairforce.one? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1451\" class=\"elementor-element elementor-element-cd1dfc1 e-con-full e-flex e-con e-child\" data-id=\"cd1dfc1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-adb5972 elementor-widget elementor-widget-text-editor\" data-id=\"adb5972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wo ist der Haken an der Sache? Ist diese Leistung f\u00fcr den Gesch\u00e4digten wirklich kostenneutral? <strong>Ja.<\/strong><\/p><p>Wenn Sie uns mit der Regulierung Ihres <strong>unverschuldeten<\/strong> Unfalls beauftragen, stellen wir f\u00fcr die Durchsetzung Ihrer Anspr\u00fcche eine Rechnung. Die Kosten richten sich nach dem Rechtsanwaltsverg\u00fctungsgesetz (RVG), also genau so, wie Sie es von jedem Rechtsanwalt kennen.<\/p><p><strong>Diese Kosten werden genau wie alle anderen Ihnen zustehenden Schadensersatzanspr\u00fcche gegen den zahlungspflichtigen Versicherer durchgesetzt.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1452\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1452\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Was kostet die Unfallregulierung mit fairforce.one? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1452\" class=\"elementor-element elementor-element-1c4f8e0 e-con-full e-flex e-con e-child\" data-id=\"1c4f8e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19e1404 elementor-widget elementor-widget-text-editor\" data-id=\"19e1404\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn Sie uns mit der Regulierung Ihres <strong>unverschuldeten<\/strong> Unfalls beauftragen, stellen wir f\u00fcr die Durchsetzung Ihrer Anspr\u00fcche eine Rechnung gem\u00e4\u00df Rechtsanwaltsverg\u00fctungsgesetz (RVG).<\/p><p>Diese Kosten werden genau wie alle anderen Anspr\u00fcche, die ihnen zustehen, gegen den zahlungspflichtigen Versicherer durchgesetzt.<\/p><p><strong>Das bedeutet f\u00fcr Sie:<\/strong><\/p><ol><li><strong> Sie selbst werden durch unsere <\/strong><strong>Geb\u00fchr nicht belastet, denn unsere Verg\u00fctung ist Teil Ihres gesetzlichen Schadenersatzanspruches. Und den erf\u00fcllt die gegnerische Versicherung.<\/strong><\/li><li><strong> Da die H\u00f6he der RVG-Verg\u00fctung gesetzlich geregelt ist und sich nach der H\u00f6he des f\u00fcr Sie erzielten Schadenersatzes berechnet, haben wir ein gemeinsames Interesse: Dass das, worauf Sie einen gesetzlichen Anspruch haben, auch wirklich vollst\u00e4ndig f\u00fcr Sie erwirkt wird.<\/strong><\/li><\/ol><p><a href=\"https:\/\/fairforce.one\/ueber-uns#finanzierung\">Weitere Information zum Thema \/ Kosten bei Eigenverschulden<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1453\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1453\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Welche Anspr\u00fcche kann fairforce.one f\u00fcr mich durchsetzen? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1453\" class=\"elementor-element elementor-element-6374aed e-flex e-con-boxed e-con e-child\" data-id=\"6374aed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2db3b1a elementor-widget elementor-widget-text-editor\" data-id=\"2db3b1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir pr\u00fcfen alle 16 Anspruchsarten, die Ihnen nach Ihrem Verkehrsunfall zustehen k\u00f6nnten. Das sind:<\/p><ul><li>Abschleppkosten<\/li><li>Ad\u00e4quater Mietwagen<\/li><li>Entgangener Urlaub<\/li><li>Fahrtkostenersatz<\/li><li>Haushaltsf\u00fchrungshilfe<\/li><li>Heilbehandlungskosten<\/li><li>Herstellergerechte Reparatur<\/li><li>Kfz-An- und Abmeldung<\/li><li>Nutzungsausfall<\/li><li>Orgapauschale<\/li><li>Pers\u00f6nlicher Sachschaden<\/li><li>Schmerzensgeld<\/li><li>Standgeb\u00fchren<\/li><li>Unabh\u00e4ngiger Gutachter<\/li><li>Verdienstausfall<\/li><li>Wertminderung<\/li><\/ul><p><a href=\"https:\/\/fairforce.one\/ratgeber\/unverschuldeter-unfall\/\" target=\"_blank\" rel=\"noopener\">Mehr zum Thema Anspruchsarten<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1454\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1454\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Warum ist fairforce.one so gut bewertet? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1454\" class=\"elementor-element elementor-element-f82c57d e-con-full e-flex e-con e-child\" data-id=\"f82c57d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be88dd0 elementor-widget elementor-widget-text-editor\" data-id=\"be88dd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>fairforce.one erh\u00e4lt so gute Bewertungen, weil die Plattform die Unfallregulierung f\u00fcr Gesch\u00e4digte besonders einfach, transparent und fair macht.<\/p><p>Unsere Nutzer sch\u00e4tzen besonders:<\/p><ul><li>Komfortable Abwicklung: Alles l\u00e4uft digital, ohne Papierkram \u2013 vom Gutachten bis zur Auszahlung.<\/li><li>Schnelligkeit: Die Erstberatung erfolgt oft innerhalb weniger Minuten, und die Bearbeitung kann sofort starten.<\/li><li>Mehrauszahlung: Kunden erzielen im Schnitt \u00fcber 480\u202f\u20ac mehr als bei der Direktabwicklung mit der Versicherung.<\/li><li>Transparente Kommunikation: \u00dcber das Kunden-Informations-System haben Nutzer jederzeit Einblick in den aktuellen Stand ihres Falls.<\/li><li>Erfahrene Partner: Unser bundesweites Netzwerk aus spezialisierten Anw\u00e4lten, Gutachtern und Werkst\u00e4tten sorgt f\u00fcr hohe Qualit\u00e4t.<\/li><li>Zertifizierte Qualit\u00e4t: fairforce.one ist nach ISO 9001 zertifiziert und wird regelm\u00e4\u00dfig vom T\u00dcV gepr\u00fcft.<\/li><\/ul><p>Kurz gesagt: fairforce.one verbindet Technologie mit Service \u2013 und das spiegelt sich in den Bewertungen wider.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1455\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1455\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Wie kontaktiere ich fairforce.one? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1455\" class=\"elementor-element elementor-element-7c412bb e-con-full e-flex e-con e-child\" data-id=\"7c412bb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d72bd10 elementor-widget elementor-widget-text-editor\" data-id=\"d72bd10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>So k\u00f6nnen Sie Kontakt mit uns aufnehmen:<\/p><ul><li>Hotline: 0800\u202f30\u202f111\u202f60<\/li><li>E-Mail: kontakt@fairforce.one<\/li><li>\u00dcber unser Webformular zur Unfallmeldung<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1456\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1456\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Warum ein gr\u00fcner Elefant? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1456\" class=\"elementor-element elementor-element-ad6cf57 e-flex e-con-boxed e-con e-child\" data-id=\"ad6cf57\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-040d3bd elementor-widget elementor-widget-text-editor\" data-id=\"040d3bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das werden wir immer wieder gefragt. Deshalb jetzt hier als eigene Rubrik.<\/p><p>Als es darum ging, welche Unternehmenswerte in unserem Brand Design erkennbar werden sollen, stand pl\u00f6tzlich ein Elefant im Raum.<\/p><p>Elefanten&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1904f3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d1904f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">sind grunds\u00e4tzlich sympathisch (jedes Kind mag Elefanten)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">schwer aus der Ruhe zu bringen <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">f\u00fcrsorglich in der eigenen Herde<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">wenn es darauf ankommt: durchsetzungsstark und schwer zu stoppen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">haben ein ausgekl\u00fcgeltes Kommunikationssystem \u00fcber gro\u00dfe Strecken<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">gehen auch f\u00fcr Peanuts die ber\u00fchmte extra-Meile<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69af354 elementor-widget elementor-widget-text-editor\" data-id=\"69af354\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Aber am wichtigsten:<\/strong><\/p><p>Dem Elefanten wird nachgesagt, dass er wenig vergisst. Unser digitaler Elefant vergisst nichts und denkt f\u00fcr Sie an alles!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-268f1aa elementor-widget elementor-widget-text-editor\" data-id=\"268f1aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Und warum gr\u00fcn?<\/strong><\/p><p>Ganz einfach: Versuchen Sie doch mal jetzt NICHT an einen gr\u00fcnen Elefanten zu denken! \ud83d\ude09<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8acfd3 elementor-widget elementor-widget-image\" data-id=\"b8acfd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/fairforce.one\/wp-content\/uploads\/2021\/06\/cropped-logo_icon_small1.png\" class=\" attachment-large size-large wp-image-69\" alt=\"Kompaktes fairforce.one Logo-Icon mit wei\u00dfem Elefantenkopf auf gr\u00fcnem Rund\" srcset=\"https:\/\/fairforce.one\/wp-content\/uploads\/2021\/06\/cropped-logo_icon_small1.png 512w, https:\/\/fairforce.one\/wp-content\/uploads\/2021\/06\/cropped-logo_icon_small1-300x300.png 300w, https:\/\/fairforce.one\/wp-content\/uploads\/2021\/06\/cropped-logo_icon_small1-150x150.png 150w, https:\/\/fairforce.one\/wp-content\/uploads\/2021\/06\/cropped-logo_icon_small1-270x270.png 270w, https:\/\/fairforce.one\/wp-content\/uploads\/2021\/06\/cropped-logo_icon_small1-192x192.png 192w, https:\/\/fairforce.one\/wp-content\/uploads\/2021\/06\/cropped-logo_icon_small1-180x180.png 180w, https:\/\/fairforce.one\/wp-content\/uploads\/2021\/06\/cropped-logo_icon_small1-32x32.png 32w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Was macht fairforce.one?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Wir bieten eine smarte, digitale Plattform zur vollst\\u00e4ndigen und fairen Abwicklung von Unfall\\u2011 und Schadensf\\u00e4llen an und greifen auf ein bundesweites Netzwerk aus gepr\\u00fcften Fachanw\\u00e4lten, Gutachtern, Werkst\\u00e4tten und Mietwagenanbietern zur\\u00fcck, um wirklich all Ihre Anspr\\u00fcche durchzusetzen.Kurz gesagt:Mit unserem Unfall-Concierge sind Sie nach Ihrem Unfall schnell wieder mobil \\u2013 ohne Stress und viel Papierkram.\"}},{\"@type\":\"Question\",\"name\":\"Wie finanziert sich fairforce.one?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Wo ist der Haken an der Sache? Ist diese Leistung f\\u00fcr den Gesch\\u00e4digten wirklich kostenneutral? Ja.Wenn Sie uns mit der Regulierung Ihres unverschuldeten Unfalls beauftragen, stellen wir f\\u00fcr die Durchsetzung Ihrer Anspr\\u00fcche eine Rechnung. Die Kosten richten sich nach dem Rechtsanwaltsverg\\u00fctungsgesetz (RVG), also genau so, wie Sie es von jedem Rechtsanwalt kennen.Diese Kosten werden genau wie alle anderen Ihnen zustehenden Schadensersatzanspr\\u00fcche gegen den zahlungspflichtigen Versicherer durchgesetzt.\"}},{\"@type\":\"Question\",\"name\":\"Was kostet die Unfallregulierung mit fairforce.one?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Wenn Sie uns mit der Regulierung Ihres unverschuldeten Unfalls beauftragen, stellen wir f\\u00fcr die Durchsetzung Ihrer Anspr\\u00fcche eine Rechnung gem\\u00e4\\u00df Rechtsanwaltsverg\\u00fctungsgesetz (RVG).Diese Kosten werden genau wie alle anderen Anspr\\u00fcche, die ihnen zustehen, gegen den zahlungspflichtigen Versicherer durchgesetzt.Das bedeutet f\\u00fcr Sie: Sie selbst werden durch unsere Geb\\u00fchr nicht belastet, denn unsere Verg\\u00fctung ist Teil Ihres gesetzlichen Schadenersatzanspruches. Und den erf\\u00fcllt die gegnerische Versicherung. Da die H\\u00f6he der RVG-Verg\\u00fctung gesetzlich geregelt ist und sich nach der H\\u00f6he des f\\u00fcr Sie erzielten Schadenersatzes berechnet, haben wir ein gemeinsames Interesse: Dass das, worauf Sie einen gesetzlichen Anspruch haben, auch wirklich vollst\\u00e4ndig f\\u00fcr Sie erwirkt wird.Weitere Information zum Thema \\\/ Kosten bei Eigenverschulden\"}},{\"@type\":\"Question\",\"name\":\"Welche Anspr\\u00fcche kann fairforce.one f\\u00fcr mich durchsetzen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Wir pr\\u00fcfen alle 16 Anspruchsarten, die Ihnen nach Ihrem Verkehrsunfall zustehen k\\u00f6nnten. Das sind:AbschleppkostenAd\\u00e4quater MietwagenEntgangener UrlaubFahrtkostenersatzHaushaltsf\\u00fchrungshilfeHeilbehandlungskostenHerstellergerechte ReparaturKfz-An- und AbmeldungNutzungsausfallOrgapauschalePers\\u00f6nlicher SachschadenSchmerzensgeldStandgeb\\u00fchrenUnabh\\u00e4ngiger GutachterVerdienstausfallWertminderungMehr zum Thema Anspruchsarten\"}},{\"@type\":\"Question\",\"name\":\"Warum ist fairforce.one so gut bewertet?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"fairforce.one erh\\u00e4lt so gute Bewertungen, weil die Plattform die Unfallregulierung f\\u00fcr Gesch\\u00e4digte besonders einfach, transparent und fair macht.Unsere Nutzer sch\\u00e4tzen besonders:Komfortable Abwicklung: Alles l\\u00e4uft digital, ohne Papierkram \\u2013 vom Gutachten bis zur Auszahlung.Schnelligkeit: Die Erstberatung erfolgt oft innerhalb weniger Minuten, und die Bearbeitung kann sofort starten.Mehrauszahlung: Kunden erzielen im Schnitt \\u00fcber 480\\u202f\\u20ac mehr als bei der Direktabwicklung mit der Versicherung.Transparente Kommunikation: \\u00dcber das Kunden-Informations-System haben Nutzer jederzeit Einblick in den aktuellen Stand ihres Falls.Erfahrene Partner: Unser bundesweites Netzwerk aus spezialisierten Anw\\u00e4lten, Gutachtern und Werkst\\u00e4tten sorgt f\\u00fcr hohe Qualit\\u00e4t.Zertifizierte Qualit\\u00e4t: fairforce.one ist nach ISO 9001 zertifiziert und wird regelm\\u00e4\\u00dfig vom T\\u00dcV gepr\\u00fcft.Kurz gesagt: fairforce.one verbindet Technologie mit Service \\u2013 und das spiegelt sich in den Bewertungen wider.\"}},{\"@type\":\"Question\",\"name\":\"Wie kontaktiere ich fairforce.one?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"So k\\u00f6nnen Sie Kontakt mit uns aufnehmen:Hotline: 0800\\u202f30\\u202f111\\u202f60E-Mail: kontakt@fairforce.one\\u00dcber unser Webformular zur Unfallmeldung\"}},{\"@type\":\"Question\",\"name\":\"Warum ein gr\\u00fcner Elefant?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Das werden wir immer wieder gefragt. Deshalb jetzt hier als eigene Rubrik.Als es darum ging, welche Unternehmenswerte in unserem Brand Design erkennbar werden sollen, stand pl\\u00f6tzlich ein Elefant im Raum.Elefanten&#8230;\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tsind grunds\\u00e4tzlich sympathisch (jedes Kind mag Elefanten)\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tschwer aus der Ruhe zu bringen \\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tf\\u00fcrsorglich in der eigenen Herde\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\twenn es darauf ankommt: durchsetzungsstark und schwer zu stoppen\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\thaben ein ausgekl\\u00fcgeltes Kommunikationssystem \\u00fcber gro\\u00dfe Strecken\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tgehen auch f\\u00fcr Peanuts die ber\\u00fchmte extra-Meile\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\tAber am wichtigsten:Dem Elefanten wird nachgesagt, dass er wenig vergisst. Unser digitaler Elefant vergisst nichts und denkt f\\u00fcr Sie an alles!\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\tUnd warum gr\\u00fcn?Ganz einfach: Versuchen Sie doch mal jetzt NICHT an einen gr\\u00fcnen Elefanten zu denken! \\ud83d\\ude09\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9966e48 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9966e48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fad fa-chevron-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt Unfall melden <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5eae2d elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5eae2d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0625c7d\" data-id=\"0625c7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38946db elementor-widget elementor-widget-heading\" data-id=\"38946db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"iso-zertifiziertes-qualitaetsmanagement\" title=\"ISO-zertifiziertes Qualit\u00e4tsmanagement\n\">ISO-zertifiziertes Qualit\u00e4tsmanagement\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aead1d2 elementor-widget elementor-widget-text-editor\" data-id=\"aead1d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bereits seit 2018, also schon im ersten Jahr nach Gr\u00fcndung, hat fairforce seine komplette Software und die darin abgebildeten Prozesse extern pr\u00fcfen und nach der ISO-Norm 9001:2015 zertifizieren lassen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-85df21f\" data-id=\"85df21f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0685e12 e-flex e-con-boxed e-con e-parent\" data-id=\"0685e12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d28a38 elementor-widget elementor-widget-image\" data-id=\"6d28a38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tms-icert.tuvsud.com\/services\/erl\/(S(21vckead4a5hhl4soxauhix0))\/erl_result.aspx?cert_id=&#038;comb1=&#038;CompName=fairforce.one&#038;Country=&#038;cScope1=&#038;md_id=3&#038;page_lang=de\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"298\" height=\"298\" src=\"https:\/\/fairforce.one\/wp-content\/uploads\/2021\/10\/ISO_9001_farbe_single.png\" class=\" attachment-medium size-medium wp-image-307\" alt=\"T\u00dcV S\u00dcD Zertifizierungssiegel f\u00fcr ISO 9001 in Farbe, Qualit\u00e4tsnachweis\" srcset=\"https:\/\/fairforce.one\/wp-content\/uploads\/2021\/10\/ISO_9001_farbe_single.png 298w, https:\/\/fairforce.one\/wp-content\/uploads\/2021\/10\/ISO_9001_farbe_single-150x150.png 150w\" sizes=\"(max-width: 298px) 100vw, 298px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be74aba elementor-widget elementor-widget-text-editor\" data-id=\"be74aba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zuletzt wurde im April 2025 nach einem ausf\u00fchrlichen Audit mit dem T\u00dcV-S\u00fcd die Aktualit\u00e4t des fairforce-Qualit\u00e4tsmanagements erneut best\u00e4tigt und zertifiziert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Unfall? Wir k\u00fcmmern uns! kostenfreie Beratung rechtssichere Unfallmeldung schnell wieder mobil fairforce koordiniert Mietwagen, Gutachten, Werkstatt, alle Versicherungen bew\u00e4hrte Pr\u00fcfung, Durchsetzung und Auszahlung aller Schadenersatz-Arten Unfall kostenfrei pr\u00fcfen In 7 Klicks zum bestbewerteten Service. kostenfreie Beratung rechtssichere Unfallmeldung schnell wieder mobil fairforce koordiniert Mietwagen, Gutachten, Werkstatt, alle Versicherungen bew\u00e4hrte Pr\u00fcfung, Durchsetzung und Auszahlung aller Schadenersatz-Arten [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":6563,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"7030,2170,5754,4289,2951,7033","_relevanssi_noindex_reason":"Yoast SEO Relevanssi index exclude","_lmt_disableupdate":"","_lmt_disable":"","yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"class_list":["post-6678","page","type-page","status-publish","hentry"],"acf":[],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/fairforce.one\/en\/wp-json\/wp\/v2\/pages\/6678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fairforce.one\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fairforce.one\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fairforce.one\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fairforce.one\/en\/wp-json\/wp\/v2\/comments?post=6678"}],"version-history":[{"count":24,"href":"https:\/\/fairforce.one\/en\/wp-json\/wp\/v2\/pages\/6678\/revisions"}],"predecessor-version":[{"id":17476,"href":"https:\/\/fairforce.one\/en\/wp-json\/wp\/v2\/pages\/6678\/revisions\/17476"}],"up":[{"embeddable":true,"href":"https:\/\/fairforce.one\/en\/wp-json\/wp\/v2\/pages\/6563"}],"wp:attachment":[{"href":"https:\/\/fairforce.one\/en\/wp-json\/wp\/v2\/media?parent=6678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}